{"id":82,"date":"2019-11-13T16:13:45","date_gmt":"2019-11-13T21:13:45","guid":{"rendered":"https:\/\/thesummittrial.com\/?page_id=82"},"modified":"2021-08-31T07:28:06","modified_gmt":"2021-08-31T11:28:06","slug":"contactenos","status":"publish","type":"page","link":"https:\/\/thesummittrial.com\/es\/contactenos\/","title":{"rendered":"Cont\u00e1ctenos"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"class_list":["post-82","page","type-page","status-publish","hentry"],"acf":[],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cont\u00e1ctenos - The SUMMIT Trial<\/title>\n<meta name=\"description\" content=\"P\u00f3ngase en contacto con el equipo de The SUMMIT Trial completando el formulario de contacto y nos pondremos en contacto con usted lo antes posible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thesummittrial.com\/es\/contactenos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cont\u00e1ctenos - The SUMMIT Trial\" \/>\n<meta property=\"og:description\" content=\"P\u00f3ngase en contacto con el equipo de The SUMMIT Trial completando el formulario de contacto y nos pondremos en contacto con usted lo antes posible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thesummittrial.com\/es\/contactenos\/\" \/>\n<meta property=\"og:site_name\" content=\"The SUMMIT Trial\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-31T11:28:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thesummittrial.com\/wp-content\/uploads\/2020\/02\/home-summit-fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheSUMMITTrial\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/contactenos\\\/\",\"url\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/contactenos\\\/\",\"name\":\"Cont\u00e1ctenos - The SUMMIT Trial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/#website\"},\"datePublished\":\"2019-11-13T21:13:45+00:00\",\"dateModified\":\"2021-08-31T11:28:06+00:00\",\"description\":\"P\u00f3ngase en contacto con el equipo de The SUMMIT Trial completando el formulario de contacto y nos pondremos en contacto con usted lo antes posible.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/contactenos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thesummittrial.com\\\/es\\\/contactenos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/contactenos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cont\u00e1ctenos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/\",\"name\":\"The SUMMIT Trial\",\"description\":\"Scaling Up Maternal Mental healthcare by Increasing access to Treatment\",\"publisher\":{\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/#organization\",\"name\":\"The SUMMIT Trial\",\"url\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thesummittrial.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-summit.png\",\"contentUrl\":\"https:\\\/\\\/thesummittrial.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-summit.png\",\"width\":1000,\"height\":833,\"caption\":\"The SUMMIT Trial\"},\"image\":{\"@id\":\"https:\\\/\\\/thesummittrial.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/TheSUMMITTrial\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cont\u00e1ctenos - The SUMMIT Trial","description":"P\u00f3ngase en contacto con el equipo de The SUMMIT Trial completando el formulario de contacto y nos pondremos en contacto con usted lo antes posible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thesummittrial.com\/es\/contactenos\/","og_locale":"es_ES","og_type":"article","og_title":"Cont\u00e1ctenos - The SUMMIT Trial","og_description":"P\u00f3ngase en contacto con el equipo de The SUMMIT Trial completando el formulario de contacto y nos pondremos en contacto con usted lo antes posible.","og_url":"https:\/\/thesummittrial.com\/es\/contactenos\/","og_site_name":"The SUMMIT Trial","article_modified_time":"2021-08-31T11:28:06+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/thesummittrial.com\/wp-content\/uploads\/2020\/02\/home-summit-fb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TheSUMMITTrial","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thesummittrial.com\/es\/contactenos\/","url":"https:\/\/thesummittrial.com\/es\/contactenos\/","name":"Cont\u00e1ctenos - The SUMMIT Trial","isPartOf":{"@id":"https:\/\/thesummittrial.com\/es\/#website"},"datePublished":"2019-11-13T21:13:45+00:00","dateModified":"2021-08-31T11:28:06+00:00","description":"P\u00f3ngase en contacto con el equipo de The SUMMIT Trial completando el formulario de contacto y nos pondremos en contacto con usted lo antes posible.","breadcrumb":{"@id":"https:\/\/thesummittrial.com\/es\/contactenos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thesummittrial.com\/es\/contactenos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thesummittrial.com\/es\/contactenos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thesummittrial.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cont\u00e1ctenos"}]},{"@type":"WebSite","@id":"https:\/\/thesummittrial.com\/es\/#website","url":"https:\/\/thesummittrial.com\/es\/","name":"The SUMMIT Trial","description":"Scaling Up Maternal Mental healthcare by Increasing access to Treatment","publisher":{"@id":"https:\/\/thesummittrial.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thesummittrial.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/thesummittrial.com\/es\/#organization","name":"The SUMMIT Trial","url":"https:\/\/thesummittrial.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/thesummittrial.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/thesummittrial.com\/wp-content\/uploads\/2019\/11\/logo-summit.png","contentUrl":"https:\/\/thesummittrial.com\/wp-content\/uploads\/2019\/11\/logo-summit.png","width":1000,"height":833,"caption":"The SUMMIT Trial"},"image":{"@id":"https:\/\/thesummittrial.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/TheSUMMITTrial"]}]}},"_links":{"self":[{"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/pages\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":2,"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/pages\/82\/revisions"}],"predecessor-version":[{"id":2852,"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/pages\/82\/revisions\/2852"}],"wp:attachment":[{"href":"https:\/\/thesummittrial.com\/es\/wp-json\/wp\/v2\/media?parent=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}